{"id":6530,"date":"2025-06-05T11:24:01","date_gmt":"2025-06-05T11:24:01","guid":{"rendered":"https:\/\/www.lesamis-saas-fee.ch\/randonnee-au-pays-des-glaciers-et-des-4000-metres\/"},"modified":"2025-06-05T11:26:37","modified_gmt":"2025-06-05T11:26:37","slug":"randonnee-au-pays-des-glaciers-et-des-4000-metres","status":"publish","type":"post","link":"https:\/\/www.lesamis-saas-fee.ch\/fr\/randonnee-au-pays-des-glaciers-et-des-4000-metres\/","title":{"rendered":"Randonn\u00e9e au pays des glaciers et des 4000 m\u00e8tres"},"content":{"rendered":"\n<p>Saas-Fee, souvent surnomm\u00e9e la \u00ab\u00a0Perle des Alpes\u00a0\u00bb, est un v\u00e9ritable paradis pour les amateurs de randonn\u00e9e. Avec la <strong>SaastalCard<\/strong>, votre s\u00e9jour sera encore plus agr\u00e9able, car elle vous permet d&rsquo;<strong>utiliser gratuitement les remont\u00e9es m\u00e9caniques<\/strong> (\u00e0 l&rsquo;exception du Metro Alpin) ainsi que le car postal dans toute la vall\u00e9e de Saas pendant votre s\u00e9jour. <\/p>\n\n<p>Imaginez que vous commencez votre journ\u00e9e par une agr\u00e9able randonn\u00e9e \u00e0 travers les for\u00eats de m\u00e9l\u00e8zes odorantes, tandis que les premiers rayons du soleil illuminent les imposants sommets de plus de 4000 m\u00e8tres qui vous entourent. Avec plus de <strong>350 km de sentiers de randonn\u00e9e balis\u00e9s<\/strong>, la r\u00e9gion offre des itin\u00e9raires pour tous les niveaux de forme physique &#8211; des promenades relaxantes aux randonn\u00e9es en montagne les plus exigeantes. <\/p>\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"681\" data-id=\"6503\" src=\"https:\/\/www.lesamis-saas-fee.ch\/wp-content\/uploads\/2025\/04\/Alpenblick-Autumn-c-Saastal-Tourismus-AG-Yannick-Lindemann-1024x681.jpg\" alt=\"Alpenblick Autumn (c) Saastal Tourismus Ag Yannick Lindemann\" class=\"wp-image-6503\" srcset=\"https:\/\/www.lesamis-saas-fee.ch\/wp-content\/uploads\/2025\/04\/Alpenblick-Autumn-c-Saastal-Tourismus-AG-Yannick-Lindemann-1024x681.jpg 1024w, https:\/\/www.lesamis-saas-fee.ch\/wp-content\/uploads\/2025\/04\/Alpenblick-Autumn-c-Saastal-Tourismus-AG-Yannick-Lindemann-300x200.jpg 300w, https:\/\/www.lesamis-saas-fee.ch\/wp-content\/uploads\/2025\/04\/Alpenblick-Autumn-c-Saastal-Tourismus-AG-Yannick-Lindemann-768x511.jpg 768w, https:\/\/www.lesamis-saas-fee.ch\/wp-content\/uploads\/2025\/04\/Alpenblick-Autumn-c-Saastal-Tourismus-AG-Yannick-Lindemann.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"427\" data-id=\"6497\" src=\"https:\/\/www.lesamis-saas-fee.ch\/wp-content\/uploads\/2025\/04\/Wandern.jpg\" alt=\"Randonn&#xE9;e\" class=\"wp-image-6497\" srcset=\"https:\/\/www.lesamis-saas-fee.ch\/wp-content\/uploads\/2025\/04\/Wandern.jpg 640w, https:\/\/www.lesamis-saas-fee.ch\/wp-content\/uploads\/2025\/04\/Wandern-300x200.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"6500\" src=\"https:\/\/www.lesamis-saas-fee.ch\/wp-content\/uploads\/2025\/04\/Wander-Triftalp-&#xA9;SaastalTourismusAG-PuzzleMedia-1024x683.jpg\" alt=\"Randonn&#xE9;e Triftalp &#xA9;saastaltourismusag Puzzlemedia\" class=\"wp-image-6500\"\/><\/figure>\n<\/figure>\n\n<p>Un point fort particulier est la possibilit\u00e9 de combiner la randonn\u00e9e et les remont\u00e9es m\u00e9caniques. Vous pouvez par exemple prendre le train jusqu&rsquo;au sommet de la montagne, profiter de la vue \u00e0 couper le souffle, puis redescendre tranquillement dans la vall\u00e9e. Ou bien vous optez pour le chemin inverse : une randonn\u00e9e exigeante en montagne jusqu&rsquo;en haut et la descente relaxante en train. Cette flexibilit\u00e9 vous permet d&rsquo;explorer les majestueuses montagnes \u00e0 votre propre rythme.   <\/p>\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"6506\" src=\"https:\/\/www.lesamis-saas-fee.ch\/wp-content\/uploads\/2025\/04\/Murmeli-Saas-Fee-&#xA9;SaastalTourismusAG-AmarcsterMedia-2.jpg\" alt=\"Marmotte Saas Fee &#xA9;saastaltourismusag Amarcstermedia (2)\" class=\"wp-image-6506\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"6509\" src=\"https:\/\/www.lesamis-saas-fee.ch\/wp-content\/uploads\/2025\/04\/Bergbahnen_Infrastruktur_Spielbodenbahn-&#xA9;SaastalTourismusAG-SaastalBergbahnenAG-2-1024x683.jpg\" alt=\"Infrastructure des remont&#xE9;es m&#xE9;caniques Spielbodenbahn &#xA9;saastaltourismusag Saastalbergbahnenag (2)\" class=\"wp-image-6509\"\/><\/figure>\n<\/figure>\n\n<p>Au cours de vos randonn\u00e9es, vous rencontrerez r\u00e9guli\u00e8rement d&rsquo;impressionnants glaciers qui fa\u00e7onnent le paysage et offrent un panorama unique. Avec un peu de chance, vous rencontrerez m\u00eame des marmottes curieuses ou des chamois et bouquetins timides, qui sont originaires de la r\u00e9gion et que l&rsquo;on peut souvent apercevoir \u00e0 proximit\u00e9 des sentiers de randonn\u00e9e. <\/p>\n\n<p>La <strong>SaastalCard<\/strong> ne vous donne pas seulement acc\u00e8s \u00e0 ces merveilles de la nature, mais vous offre \u00e9galement de nombreuses r\u00e9ductions sur d&rsquo;autres activit\u00e9s dans la r\u00e9gion. Profitez-en pour d\u00e9couvrir la vall\u00e9e de Saas sous toutes ses facettes et engranger des souvenirs inoubliables. <\/p>\n\n<p><strong>Avantages de la SaastalCard :<\/strong><\/p>\n\n<ul class=\"wp-block-list\">\n<li>Utilisation gratuite de neuf remont\u00e9es m\u00e9caniques dans la vall\u00e9e de Saas (sauf Metro Alpin).<\/li>\n\n\n\n<li>Voyagez gratuitement avec CarPostal dans les quatre communes de la vall\u00e9e de Saas.<\/li>\n\n\n\n<li>R\u00e9ductions jusqu&rsquo;\u00e0 30% sur diverses offres locales et r\u00e9gionales.<\/li>\n<\/ul>\n\n<p><strong>Randonn\u00e9e dans la vall\u00e9e de Saas<\/strong><\/p>\n\n<ul class=\"wp-block-list\">\n<li>350 km de sentiers de randonn\u00e9e balis\u00e9s<\/li>\n\n\n\n<li>Randonn\u00e9e face \u00e0 18 sommets de plus de 4000 m\u00e8tres et de nombreux glaciers<\/li>\n\n\n\n<li>Il y en a pour tous les go\u00fbts : des promenades faciles, des sentiers th\u00e9matiques passionnants, des randonn\u00e9es en haute montagne, des for\u00eats de r\u00eave et des vall\u00e9es isol\u00e9es.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Randonn\u00e9e au pays des glaciers et des 4000<br \/>\nAvantages Saastal-Card<br \/>\nUtilisation gratuite de neuf remont\u00e9es m\u00e9caniques dans la vall\u00e9e de Saas (sauf Metro Alpin).<\/p>\n<p>Libre circulation avec le CarPostal dans les quatre communes de la vall\u00e9e de Saas.<br \/>\nR\u00e9ductions jusqu&rsquo;\u00e0 30% sur diverses offres locales et r\u00e9gionales.<\/p>\n","protected":false},"author":4,"featured_media":6502,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"slim_seo":{"title":"Randonn\u00e9e au pays des glaciers et des 4000 - H\u00f4tel Les Amis","description":"Randonn\u00e9e dans la vall\u00e9e de Saas avec utilisation gratuite des remont\u00e9es m\u00e9caniques gr\u00e2ce \u00e0 la SaastalCard. D\u00e9couvrez des glaciers, des sommets de 4000 m\u00e8tres et 350 km de sentiers de randonn\u00e9e pour tous les niveaux."},"footnotes":""},"categories":[21],"tags":[32,29,31,30],"class_list":["post-6530","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general-fr","tag-les-amis-fr","tag-randonnee","tag-saas-fee-fr","tag-saastalcard-fr"],"spectra_custom_meta":{"_pingme":["1"],"_encloseme":["1"],"slim_seo":["a:2:{s:5:\"title\";s:61:\"Randonn\u00e9e au pays des glaciers et des 4000 - H\u00f4tel Les Amis\";s:11:\"description\";s:226:\"Randonn\u00e9e dans la vall\u00e9e de Saas avec utilisation gratuite des remont\u00e9es m\u00e9caniques gr\u00e2ce \u00e0 la SaastalCard. D\u00e9couvrez des glaciers, des sommets de 4000 m\u00e8tres et 350 km de sentiers de randonn\u00e9e pour tous les niveaux. \";}"],"_thumbnail_id":["6502"],"_last_translation_edit_mode":["translation-editor"],"_wpml_word_count":["490"],"_uag_css_file_name":["uag-css-6530.css"],"_uagb_previous_block_counts":["a:90:{s:21:\"uagb\/advanced-heading\";i:0;s:15:\"uagb\/blockquote\";i:0;s:12:\"uagb\/buttons\";i:0;s:18:\"uagb\/buttons-child\";i:0;s:19:\"uagb\/call-to-action\";i:0;s:15:\"uagb\/cf7-styler\";i:0;s:11:\"uagb\/column\";i:0;s:12:\"uagb\/columns\";i:0;s:14:\"uagb\/container\";i:0;s:21:\"uagb\/content-timeline\";i:0;s:27:\"uagb\/content-timeline-child\";i:0;s:14:\"uagb\/countdown\";i:0;s:12:\"uagb\/counter\";i:0;s:8:\"uagb\/faq\";i:0;s:14:\"uagb\/faq-child\";i:0;s:10:\"uagb\/forms\";i:0;s:17:\"uagb\/forms-accept\";i:0;s:19:\"uagb\/forms-checkbox\";i:0;s:15:\"uagb\/forms-date\";i:0;s:16:\"uagb\/forms-email\";i:0;s:17:\"uagb\/forms-hidden\";i:0;s:15:\"uagb\/forms-name\";i:0;s:16:\"uagb\/forms-phone\";i:0;s:16:\"uagb\/forms-radio\";i:0;s:17:\"uagb\/forms-select\";i:0;s:19:\"uagb\/forms-textarea\";i:0;s:17:\"uagb\/forms-toggle\";i:0;s:14:\"uagb\/forms-url\";i:0;s:14:\"uagb\/gf-styler\";i:0;s:15:\"uagb\/google-map\";i:0;s:11:\"uagb\/how-to\";i:0;s:16:\"uagb\/how-to-step\";i:0;s:9:\"uagb\/icon\";i:0;s:14:\"uagb\/icon-list\";i:0;s:20:\"uagb\/icon-list-child\";i:0;s:10:\"uagb\/image\";i:0;s:18:\"uagb\/image-gallery\";i:0;s:13:\"uagb\/info-box\";i:0;s:18:\"uagb\/inline-notice\";i:0;s:11:\"uagb\/lottie\";i:0;s:21:\"uagb\/marketing-button\";i:0;s:10:\"uagb\/modal\";i:0;s:18:\"uagb\/popup-builder\";i:0;s:16:\"uagb\/post-button\";i:0;s:18:\"uagb\/post-carousel\";i:0;s:17:\"uagb\/post-excerpt\";i:0;s:14:\"uagb\/post-grid\";i:0;s:15:\"uagb\/post-image\";i:0;s:17:\"uagb\/post-masonry\";i:0;s:14:\"uagb\/post-meta\";i:0;s:18:\"uagb\/post-taxonomy\";i:0;s:18:\"uagb\/post-timeline\";i:0;s:15:\"uagb\/post-title\";i:0;s:20:\"uagb\/restaurant-menu\";i:0;s:26:\"uagb\/restaurant-menu-child\";i:0;s:11:\"uagb\/review\";i:0;s:12:\"uagb\/section\";i:0;s:14:\"uagb\/separator\";i:0;s:11:\"uagb\/slider\";i:0;s:17:\"uagb\/slider-child\";i:0;s:17:\"uagb\/social-share\";i:0;s:23:\"uagb\/social-share-child\";i:0;s:16:\"uagb\/star-rating\";i:0;s:23:\"uagb\/sure-cart-checkout\";i:0;s:22:\"uagb\/sure-cart-product\";i:0;s:15:\"uagb\/sure-forms\";i:0;s:22:\"uagb\/table-of-contents\";i:0;s:9:\"uagb\/tabs\";i:0;s:15:\"uagb\/tabs-child\";i:0;s:18:\"uagb\/taxonomy-list\";i:0;s:9:\"uagb\/team\";i:0;s:16:\"uagb\/testimonial\";i:0;s:14:\"uagb\/wp-search\";i:0;s:19:\"uagb\/instagram-feed\";i:0;s:10:\"uagb\/login\";i:0;s:17:\"uagb\/loop-builder\";i:0;s:18:\"uagb\/loop-category\";i:0;s:20:\"uagb\/loop-pagination\";i:0;s:15:\"uagb\/loop-reset\";i:0;s:16:\"uagb\/loop-search\";i:0;s:14:\"uagb\/loop-sort\";i:0;s:17:\"uagb\/loop-wrapper\";i:0;s:13:\"uagb\/register\";i:0;s:19:\"uagb\/register-email\";i:0;s:24:\"uagb\/register-first-name\";i:0;s:23:\"uagb\/register-last-name\";i:0;s:22:\"uagb\/register-password\";i:0;s:30:\"uagb\/register-reenter-password\";i:0;s:19:\"uagb\/register-terms\";i:0;s:22:\"uagb\/register-username\";i:0;}"],"_uag_page_assets":["a:9:{s:3:\"css\";s:2318:\".uag-blocks-common-selector{z-index:var(--z-index-desktop) !important}@media(max-width: 976px){.uag-blocks-common-selector{z-index:var(--z-index-tablet) !important}}@media(max-width: 767px){.uag-blocks-common-selector{z-index:var(--z-index-mobile) !important}}.wp-block-uagb-advanced-heading h1,.wp-block-uagb-advanced-heading h2,.wp-block-uagb-advanced-heading h3,.wp-block-uagb-advanced-heading h4,.wp-block-uagb-advanced-heading h5,.wp-block-uagb-advanced-heading h6,.wp-block-uagb-advanced-heading p,.wp-block-uagb-advanced-heading div{word-break:break-word}.wp-block-uagb-advanced-heading .uagb-heading-text{margin:0}.wp-block-uagb-advanced-heading .uagb-desc-text{margin:0}.wp-block-uagb-advanced-heading .uagb-separator{font-size:0;border-top-style:solid;display:inline-block;margin:0 0 10px 0}.wp-block-uagb-advanced-heading .uagb-highlight{color:#f78a0c;border:0;transition:all .3s ease}.uag-highlight-toolbar{border-left:0;border-top:0;border-bottom:0;border-radius:0;border-right-color:#1e1e1e}.uag-highlight-toolbar .components-button{border-radius:0;outline:none}.uag-highlight-toolbar .components-button.is-primary{color:#fff}.wp-block-uagb-advanced-heading.uagb-block-7f4b4e83.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-0);}.wp-block-uagb-advanced-heading.uagb-block-7f4b4e83.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-7f4b4e83.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-7f4b4e83.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-7f4b4e83.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-7f4b4e83 .uagb-heading-text{font-weight: 500;font-size: 24px;}@media only screen and (max-width: 976px) {.wp-block-uagb-advanced-heading.uagb-block-7f4b4e83 .uagb-heading-text{font-size: 17px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-advanced-heading.uagb-block-7f4b4e83 .uagb-heading-text{font-size: 22px;}}\";s:2:\"js\";s:0:\"\";s:18:\"current_block_list\";a:13:{i:0;s:14:\"core\/paragraph\";i:1;s:12:\"core\/gallery\";i:2;s:10:\"core\/image\";i:3;s:9:\"core\/list\";i:4;s:14:\"core\/list-item\";i:5;s:13:\"surecart\/cart\";i:6;s:20:\"surecart\/cart-header\";i:7;s:19:\"surecart\/cart-items\";i:8;s:20:\"surecart\/cart-coupon\";i:9;s:22:\"surecart\/cart-subtotal\";i:10;s:28:\"surecart\/cart-bump-line-item\";i:11;s:20:\"surecart\/cart-submit\";i:12;s:21:\"uagb\/advanced-heading\";}s:8:\"uag_flag\";b:1;s:11:\"uag_version\";s:10:\"1778675747\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":["https:\/\/www.lesamis-saas-fee.ch\/wp-content\/uploads\/2025\/04\/Wander-Triftalp-\u00a9SaastalTourismusAG-PuzzleMedia.jpg",1200,800,false],"thumbnail":["https:\/\/www.lesamis-saas-fee.ch\/wp-content\/uploads\/2025\/04\/Wander-Triftalp-\u00a9SaastalTourismusAG-PuzzleMedia-150x150.jpg",150,150,true],"medium":["https:\/\/www.lesamis-saas-fee.ch\/wp-content\/uploads\/2025\/04\/Wander-Triftalp-\u00a9SaastalTourismusAG-PuzzleMedia-300x200.jpg",300,200,true],"medium_large":["https:\/\/www.lesamis-saas-fee.ch\/wp-content\/uploads\/2025\/04\/Wander-Triftalp-\u00a9SaastalTourismusAG-PuzzleMedia-768x512.jpg",768,512,true],"large":["https:\/\/www.lesamis-saas-fee.ch\/wp-content\/uploads\/2025\/04\/Wander-Triftalp-\u00a9SaastalTourismusAG-PuzzleMedia-1024x683.jpg",1024,683,true],"1536x1536":["https:\/\/www.lesamis-saas-fee.ch\/wp-content\/uploads\/2025\/04\/Wander-Triftalp-\u00a9SaastalTourismusAG-PuzzleMedia.jpg",1200,800,false],"2048x2048":["https:\/\/www.lesamis-saas-fee.ch\/wp-content\/uploads\/2025\/04\/Wander-Triftalp-\u00a9SaastalTourismusAG-PuzzleMedia.jpg",1200,800,false]},"uagb_author_info":{"display_name":"Les Amis","author_link":"https:\/\/www.lesamis-saas-fee.ch\/fr\/author\/lesamis\/"},"uagb_comment_info":0,"uagb_excerpt":"Randonn\u00e9e au pays des glaciers et des 4000 Avantages Saastal-Card Utilisation gratuite de neuf remont\u00e9es m\u00e9caniques dans la vall\u00e9e de Saas (sauf Metro Alpin). Libre circulation avec le CarPostal dans les quatre communes de la vall\u00e9e de Saas. R\u00e9ductions jusqu'\u00e0 30% sur diverses offres locales et r\u00e9gionales.","_links":{"self":[{"href":"https:\/\/www.lesamis-saas-fee.ch\/fr\/wp-json\/wp\/v2\/posts\/6530","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lesamis-saas-fee.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lesamis-saas-fee.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lesamis-saas-fee.ch\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lesamis-saas-fee.ch\/fr\/wp-json\/wp\/v2\/comments?post=6530"}],"version-history":[{"count":1,"href":"https:\/\/www.lesamis-saas-fee.ch\/fr\/wp-json\/wp\/v2\/posts\/6530\/revisions"}],"predecessor-version":[{"id":6531,"href":"https:\/\/www.lesamis-saas-fee.ch\/fr\/wp-json\/wp\/v2\/posts\/6530\/revisions\/6531"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lesamis-saas-fee.ch\/fr\/wp-json\/wp\/v2\/media\/6502"}],"wp:attachment":[{"href":"https:\/\/www.lesamis-saas-fee.ch\/fr\/wp-json\/wp\/v2\/media?parent=6530"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lesamis-saas-fee.ch\/fr\/wp-json\/wp\/v2\/categories?post=6530"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lesamis-saas-fee.ch\/fr\/wp-json\/wp\/v2\/tags?post=6530"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}